{"id":63606,"date":"2025-02-11T14:29:01","date_gmt":"2025-02-11T14:29:01","guid":{"rendered":"http:\/\/performers.cam4.com\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro-2\/"},"modified":"2025-02-11T14:29:45","modified_gmt":"2025-02-11T14:29:45","slug":"concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro","status":"publish","type":"post","link":"https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/","title":{"rendered":"Concurso de fotos sensuais Valentine\u00b4s Day \u2661 Ganhe um dos 35 pr\u00eamios e at\u00e9 US$ 100 (12 a 16 de fevereiro)"},"content":{"rendered":"<h2>O Valentine\u00b4s Day \u00e9 <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">a melhor \u00e9poca do ano para receber todo o amor dos seus f\u00e3s no CAM4.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Mostre-nos seu lado mais sexy e rom\u00e2ntico em um show para ganhar at\u00e9 $ 100<\/span><\/span><\/span> \u2665<\/h2>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-63599\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Theme-Shows-Valentines-Day-2025-Banners.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Theme-Shows-Valentines-Day-2025-Banners.jpg 1600w, https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Theme-Shows-Valentines-Day-2025-Banners-300x169.jpg 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Theme-Shows-Valentines-Day-2025-Banners-768x432.jpg 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Theme-Shows-Valentines-Day-2025-Banners-750x422.jpg 750w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/h2>\n<h2><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Entre quarta-feira, 12 de fevereiro e domingo, 16 de fevereiro, fa\u00e7a um show ao vivo\u00a0 #CAM4Valentine e publique uma foto ou v\u00eddeo sexy com tema Valentine\u00b4s Day no X para ganhar at\u00e9 US$ 100!<\/span><\/span> <span class=\"jCAhz\"><span class=\"ryNqvb\">(perfil X obrigat\u00f3rio).<\/span><\/span><\/span><br \/>\n <\/strong><\/h2>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-35031\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/valentine-panty.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/h3>\n<h3><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">35 PR\u00caMIOS PARA OS TWEETS MAIS SEXY E ORIGINAIS<\/span><\/span><\/span><\/h3>\n<h3>1 Pr\u00eamio Miss CAM4 Valentine <strong><b>\u2661 <\/b><\/strong><strong>100$ \u00a0<\/strong><\/h3>\n<h3>1 Pr\u00eamio Mister CAM4 Valentine <b>\u2661 100$<\/b><\/p>\n<p> \u00a0 3 Pr\u00eamios Best CAM4 Valentine \u00a0<b>\u2665 50$<\/p>\n<p> <\/b>5 Pr\u00eamios Sexy CAM4 Valentine <b>\u2665 25$<br \/>\n <\/b><\/h3>\n<h3><b>\u00a0 <\/b>25 Pr\u00eamios CAM4 Valentine\u00a0 <b>\u2765 <\/b><b>10$<\/b><\/h3>\n<h3><img decoding=\"async\" src=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2025\/01\/b777c_vday-dog.gif\" \/><br \/>\n <strong>~ Como participar<\/strong><strong>:<br \/>\n <\/strong><\/h3>\n<p><strong><span class=\"\" lang=\"it\" tabindex=\"-1\"><br \/>\n \u2764\u00a0 <\/span><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Agende um show no seu calend\u00e1rio de transmiss\u00e3o *para ser realizado entre quarta-feira, 12 de fevereiro, e domingo, 16 de fevereiro, inserindo o seguinte tag na descri\u00e7\u00e3o:<\/span><\/span><\/span>#CAM4Valentine<br \/>\n <\/strong><a href=\"https:\/\/pt.cam4.com\/training\/iniciando-cam4\/como-agendar-seus-shows\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Clique aqui se voc\u00ea n\u00e3o sabe como agendar um show em seu calend\u00e1rio<\/span><\/span><\/span><\/a><\/p>\n<p><strong><span class=\"\" lang=\"it\" tabindex=\"-1\"><br \/>\n \u2764<\/span> Use a hashtag #CAM4Valentine <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">na descri\u00e7\u00e3o do seu show quando voc\u00ea estiver transmitindo no CAM4.<\/span><\/span><\/span><br \/>\n <\/strong><\/p>\n<p><strong><span class=\"\" lang=\"it\" tabindex=\"-1\"><br \/>\n \u2764<\/span><\/strong>\u00a0<strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Pouco antes do show ou durante, poste no X (Twitter) <\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">uma foto SOFT &#8211; sem mostrar genitais ou cenas de sexo &#8211; sobre o tema, <\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">o link para o seu perfil CAM4 e as<\/span><\/span><\/span> <\/strong><strong>hashtags<\/strong> <strong>#<\/strong><strong>CAM4Valentine <\/strong>e <strong>#CAM4<\/strong><span id=\"result_box\" class=\"\" lang=\"it\" tabindex=\"-1\"><\/span>.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-35030\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/heart_brief.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/h2>\n<p><em><strong><span id=\"result_box\" class=\"\" lang=\"it\" tabindex=\"-1\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">No final do concurso, os gerentes regionais do CAM4 de cada pa\u00eds participante julgar\u00e3o os melhores shows e tweets com fotos ou v\u00eddeos com base na qualidade e criatividade do conte\u00fado e no comprometimento geral dos artistas.<\/span><\/span><\/span><\/span> <\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-58996 size-full\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/valentine-cam.png\" alt=\"\" width=\"594\" height=\"415\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/valentine-cam.png 594w, https:\/\/performers.cam4.com\/wp-content\/uploads\/valentine-cam-300x210.png 300w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/p>\n<h2><span class=\"\" lang=\"it\" tabindex=\"-1\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Est\u00e1 ficando sem ideias para seus shows picantes?<\/span><\/span><\/span><br \/>\n <\/span><\/h2>\n<p><span class=\"\" lang=\"it\" tabindex=\"-1\"><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">As cores do amor s\u00e3o vermelho e rosa&#8230; lingerie sexy neste tom encantar\u00e1 seus f\u00e3s!<\/span><\/span><\/span><\/strong><\/span><\/p>\n<p><span class=\"\" lang=\"it\" tabindex=\"-1\"><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">P\u00e9talas, rosas, chocolates, morangos, creme, cora\u00e7\u00f5es, bal\u00f5es&#8230;\u00a0 lhe dizem alguma coisa?<\/span><\/span> <span class=\"jCAhz\"><span class=\"ryNqvb\">Temos certeza que voc\u00ea conseguir\u00e1 nos surpreender<\/span><\/span><\/span> \u2764<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63572\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/best_cam4valentines.png\" alt=\"\" width=\"885\" height=\"1132\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/best_cam4valentines.png 885w, https:\/\/performers.cam4.com\/wp-content\/uploads\/best_cam4valentines-235x300.png 235w, https:\/\/performers.cam4.com\/wp-content\/uploads\/best_cam4valentines-768x982.png 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/best_cam4valentines-586x750.png 586w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/p>\n<p><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Lembre-se de twittar fotos SOFT para este concurso:<\/span><\/span><\/span><br \/>\n <\/strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">PROIBIDO cenas de sexo,\u00a0 genitais ( test\u00edculos, p\u00eanis ou vagina)<\/span><\/span><\/span><br \/>\n &#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">PERMITIDO\u00a0 mamilos,\u00a0 bunda.<\/span><\/span><\/span><\/p>\n<p><strong>\u00a4 <\/strong><em><a href=\"https:\/\/pt.cam4.com\/training\/midia-social\/adicionado-o-seu-twitter-no-cam4-com-twitter-connect\" target=\"_blank\" rel=\"noopener\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Dicas para fotos: <\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Tente twittar fotos em boa resolu\u00e7\u00e3o, criativas e sem logotipos ou descri\u00e7\u00f5es.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Voc\u00ea tamb\u00e9m pode tuitar mais conte\u00fado para aumentar suas chances de ganhar.<\/span><\/span> <span class=\"jCAhz\"><span class=\"ryNqvb\">Descubra aqui como conectar sua conta X ao CAM4 atrav\u00e9s do<\/span><\/span><\/span> twitter connect<\/a>.<\/p>\n<p> <\/em><\/p>\n<h2><strong>Veja a galeria dos vencedores <a href=\"https:\/\/pt.cam4.com\/blog\/as-fotos-mais-sexy-do-valentines-day-de-2024-cam4\/\">do Valentine\u00b4s Day 2024 @CAM4<\/a><\/strong><\/h2>\n<p><a href=\"https:\/\/it.cam4.com\/blog\/foto-sexy-san-valentino-2024-cam4\/\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/it.cam4.com\/blog\/wp-content\/blogs.dir\/3\/files\/2024\/02\/eva_macalliter-banner.jpg\" \/><\/a><strong>_________________________________________<br \/>\n <\/strong><\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-35027 alignleft\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/strawberry-dipped.png\" alt=\"\" width=\"68\" height=\"68\" \/><\/h2>\n<h4><strong>~ Regras<\/strong><\/h4>\n<p>~ <em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Concurso reservado para artistas com conta verificada no Performer dashboard.<\/span><\/span><\/span><\/p>\n<p> ~ A tag <strong>#CAM4Valentine<\/strong> <\/em><em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">precisar\u00e1 ser inserido na descri\u00e7\u00e3o do seu show<\/span><\/span><\/span><\/p>\n<p> &#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O show dever\u00e1 ser planejado e realizado entre 12 e 16 de fevereiro de 2025.<\/span><\/span><\/span><br \/>\n <\/em><em><br \/>\n ~<span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O show e a foto tuitada devem ter como tema o Valentine\u00b4s Day <\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">(fotos e shows n\u00e3o tem\u00e1ticos e n\u00e3o Soft n\u00e3o ser\u00e3o considerados v\u00e1lidos)<\/span><\/span><\/span><br \/>\n <\/em><\/p>\n<p>~<em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">As fotos e v\u00eddeos tuitados devem ser conte\u00fado novo e o show deve ser realizado ao vivo no CAM4.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Fotos e v\u00eddeos tuitados em edi\u00e7\u00f5es anteriores n\u00e3o ser\u00e3o levados em considera\u00e7\u00e3o.<\/span><\/span><\/span><br \/>\n ~ <\/em><em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O perfil X deve estar vinculado ao seu perfil CAM4: <\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">conecte-o na se\u00e7\u00e3o M\u00eddias Sociais das op\u00e7\u00f5es da sua conta (se seu perfil n\u00e3o estiver conectado, n\u00e3o poderemos verificar sua participa\u00e7\u00e3o).<\/span><\/span><\/span><\/p>\n<p> ~\u00a0<\/em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Seu perfil X deve ser p\u00fablico (n\u00e3o privado) para participar.<\/span><\/span><\/span><\/p>\n<p><em><strong>OBS:\u00a0<span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Somente os performers que ganharam pelo menos US$ 25 (250 tokens) entre 15 de janeiro e 16 de fevereiro de 2025 poder\u00e3o ganhar um dos pr\u00eamios no valor de US$ 100, US$ 50 e US$ 25.<\/span><\/span><\/span><\/strong><\/em><\/p>\n<p><em><span class=\"fabric-text-color-mark\" data-renderer-mark=\"true\" data-text-custom-color=\"#4c9aff\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Os performers que ganharem menos de 250 fichas ainda poder\u00e3o ganhar os pr\u00eamios restantes de US$ 10.<\/span><\/span><\/span><br \/>\n <\/span><\/em><em><br \/>\n <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-58993 size-full\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/valentines-blog.jpg\" alt=\"\" width=\"1280\" height=\"693\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/valentines-blog.jpg 1280w, https:\/\/performers.cam4.com\/wp-content\/uploads\/valentines-blog-300x162.jpg 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/valentines-blog-768x416.jpg 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/valentines-blog-750x406.jpg 750w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/em><em><br \/>\n <\/em><\/p>\n<div class=\"m-entry__feedback\"><div class=\"m-feedback-prompt\">\n\t\t  <h4 class=\"m-feedback-prompt__header\">Was this article helpful?<\/h4>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt__social m-feedback-prompt__social_thumbsup yes\" data-analytics-link=\"feedback-prompt:yes\">\n\t\t    <i class=\"fa fa-thumbs-up\">&nbsp;<\/i>\n\t\t  <\/a>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt_form no\" data-analytics-link=\"feedback-prompt:no\">\n\t\t    <i class=\"fa fa-thumbs-down\">&nbsp;<\/i>\n\t\t  <\/a><br>\n\t\t  <div class=\"m-feedback-prompt__display m-feedback-prompt__social yes\">\n\t\t    <p class=\"m-feedback-prompt__text\">Awesome, share it:<\/p>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon facebook fa fa-facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Share<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon twitter fa fa-twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/&text=Concurso de fotos sensuais Valentine\u00b4s Day \u2661 Ganhe um dos 35 pr\u00eamios e at\u00e9 US$ 100 (12 a 16 de fevereiro)\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Tweet<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon googleplus fa fa-google-plus\" href=\"https:\/\/plus.google.com\/share?url=https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Google Plus<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon linkedin fa fa-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/&title=Concurso de fotos sensuais Valentine\u00b4s Day \u2661 Ganhe um dos 35 pr\u00eamios e at\u00e9 US$ 100 (12 a 16 de fevereiro)\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">LinkedIn<\/span>\n\t\t    <\/a>\n\t\t  <\/div>\n\t\t  \t<div class=\"m-feedback-prompt__display m-feedback-prompt__form no\">\n\t\t  \t<div class=\"thanks feedback-nodisplayall\"><h2>Thanks!<h2><div class=\"m-contact\"><p>Thanks for getting in touch with us.<\/p><\/div><\/div>\n\t\t    <form id=\"contact-form\" class=\"new_support_request\" action=\"\" accept-charset=\"UTF-8\" method=\"post\">\n\t\t    <input type=\"hidden\" id=\"authenticity_token\" name=\"authenticity_token\" value=\"5548f92a60\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/posts\/63606\" \/>\n\t\t      <input value=\"https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/\" type=\"hidden\" name=\"currenturl\" id=\"currenturl\">\n\t\t      <input value=\"Concurso de fotos sensuais Valentine\u00b4s Day \u2661 Ganhe um dos 35 pr\u00eamios e at\u00e9 US$ 100 (12 a 16 de fevereiro)\" type=\"hidden\" name=\"currenttitle\" id=\"currenttitle\">\n\t\t      <label class=\"is-required\">Help us improve. Give us your feedback:<\/label>\n\t\t      <textarea class=\"p-input__textarea\" name=\"feedbackmessage\" id=\"feedbackmessage\"><\/textarea>\n\t\t      <label class=\"is-required\">Your Full Name:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"feedbackfullname\" id=\"feedbackfullname\">\n\t\t      <label class=\"is-required\">Your email address:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"mailinglistemail\" id=\"mailinglistemail\">\n\t\t      <div class=\"feedback-message\" id=\"feedback-message\"><\/div>\n\t\t      <div class=\"__submit\">\n\t\t        <input type=\"submit\" name=\"commit\" value=\"Submit\" class=\"p-button\" id=\"submit-contact-form\" data-analytics-link=\"feedback-prompt:submit\">\n\t\t      <\/div>\n\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>O Valentine\u00b4s Day \u00e9 a melhor \u00e9poca do ano para receber todo o amor dos seus f\u00e3s no CAM4. Mostre-nos seu lado mais sexy e rom\u00e2ntico em um show para ganhar at\u00e9 $ 100 \u2665 Entre quarta-feira, 12 de fevereiro e domingo, 16 de fevereiro, fa\u00e7a um show ao vivo\u00a0 #CAM4Valentine e publique uma foto &hellip; <a href=\"https:\/\/performers.cam4.com\/pt-pt\/concurso-de-fotos-sensuais-valentines-day-ganhe-um-dos-35-premios-e-ate-us-100-12-a-16-de-fevereiro\/\" class=\"more-link\">Continuar a ler<span class=\"screen-reader-text\">Concurso de fotos sensuais Valentine\u00b4s Day \u2661 Ganhe um dos 35 pr\u00eamios e at\u00e9 US$ 100 (12 a 16 de fevereiro)<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[835],"tags":[],"class_list":["post-63606","post","type-post","status-publish","format-standard","hentry","category-cam4-concursos"],"acf":[],"_links":{"self":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=63606"}],"version-history":[{"count":1,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63606\/revisions"}],"predecessor-version":[{"id":63607,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63606\/revisions\/63607"}],"wp:attachment":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=63606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=63606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=63606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}