{"id":60304,"date":"2024-05-21T15:39:29","date_gmt":"2024-05-21T15:39:29","guid":{"rendered":"http:\/\/performers.cam4.com\/?p=60304"},"modified":"2024-06-12T17:30:57","modified_gmt":"2024-06-12T17:30:57","slug":"faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho","status":"publish","type":"post","link":"https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/","title":{"rendered":"Fa\u00e7a uma viagem libertina para Spicy Island na Cro\u00e1cia com CAM4 &#8211; Ganhadora"},"content":{"rendered":"<h2 class=\"has-text-align-center\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz JxVs2d ChMk0b\"><span class=\"ryNqvb\">Parab\u00e9ns \u00e0 radiante<\/span><\/span><\/span> <a href=\"https:\/\/it.cam4.com\/NICOLE_98\" target=\"_blank\" rel=\"noreferrer noopener\">Nicole_98\u00a0<\/a>\ud83c\udf1f<span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz JxVs2d ChMk0b\"><span class=\"ryNqvb\">vencedora da competi\u00e7\u00e3o CAM4 Spicy Island 2024! <\/span><\/span><a href=\"https:\/\/pt.cam4.com\/blog\/nicole_98-sai-de-ferias-com-o-cam4-na-spicy-island-%f0%9f%8f%9d%ef%b8%8f%f0%9f%94%a5\/\"><span class=\"jCAhz JxVs2d ChMk0b\"><span class=\"ryNqvb\">Clique aqui e descubra quem ela vai levar de f\u00e9rias para a ilha do prazer.<\/span><\/span><\/a><\/span><\/h2>\n<h3><span class=\"HwtZe\" lang=\"pt\">\u00a0<\/span><\/h3>\n<h3><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Participe do nosso concurso de 27 de maio a 9 de junho de 2024 para ganhar uma viagem onde voc\u00ea poder\u00e1 criar conte\u00fado com at\u00e9 tr\u00eas amigos na Spicy Island, Cro\u00e1cia, de 2 a 6 de julho.<\/span><\/span><\/span><\/h3>\n<h4><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calling all female european content creators!&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:33554945,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0,&quot;28&quot;:1}\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60323\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/LEVEL-UP-STARS.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/LEVEL-UP-STARS.jpg 1600w, https:\/\/performers.cam4.com\/wp-content\/uploads\/LEVEL-UP-STARS-300x169.jpg 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/LEVEL-UP-STARS-768x432.jpg 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/LEVEL-UP-STARS-750x422.jpg 750w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/span><\/span><\/span><\/span><\/h4>\n<p><strong>O que \u00e9 a Spicy Island ?<\/p>\n<p> Spicy Island<\/strong> <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00e9 uma ilha privada de 136 hectares na costa da Cro\u00e1cia, perto de Sibenik, no cristalino Mar Adri\u00e1tico e perto das Ilhas Kornati.<\/span><\/span> <strong><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">\u00c9 um ponto de encontro de liberais e criadores de conte\u00fado adulto.<\/span><\/span><\/strong><\/span><\/p>\n<p> <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">CAM4 oferece a voc\u00ea a oportunidade de ganhar <strong>uma viagem com tudo inclu\u00eddo<\/strong> e ficar em um bangal\u00f4 de dois quartos para at\u00e9 quatro pessoas nesta ilha paradis\u00edaca (os detalhes ser\u00e3o comunicados ao vencedor)<\/span><\/span><\/span><\/p>\n<p> <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O concurso est\u00e1 aberto a todos os modelos CAM4 <strong>residentes na Europa<\/strong> (tamb\u00e9m \u00e9 poss\u00edvel registrar-se com outro modelo CAM4\/Tempted)<\/span><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60345\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/spicy2.png\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy2.png 1000w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy2-300x200.png 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy2-768x512.png 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy2-750x500.png 750w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h3>\u00a0<strong><br \/>\n Como posso participar?<\/strong><\/h3>\n<p><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Para participar do concurso voc\u00ea deve atender a alguns requisitos:<\/span><\/span><\/span><\/p>\n<p> <strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Ter ganho um m\u00ednimo de US$ 300 nos 30 dias anteriores ao in\u00edcio do concurso (entre 26 de abril e 26 de maio)<\/span><\/span><\/span><\/strong><br \/>\n <strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Ter uma conta no Twitter conectada ao seu CAM4\/Tempted<\/span><\/span><\/span><br \/>\n <\/strong><strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Mostrar o seu rosto em seus shows e publica\u00e7\u00f5es<\/span><\/span><\/span><br \/>\n &#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Preencher o formul\u00e1rio do Google nesta p\u00e1gina (abaixo) com seu nome de usu\u00e1rio CAM4<\/span><\/span><\/span><br \/>\n <\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60356\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/452cf_cruise-ship.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p> <\/strong><strong><span class=\"HwtZe\" lang=\"fr\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">QUAL \u00c9 O PREMIO ?<\/span><\/span><\/span><\/p>\n<p> <\/strong><span class=\"HwtZe\" lang=\"fr\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O\/a ganhadora receber\u00e1 uma <strong><span class=\"HwtZe\" lang=\"pt\">viagem com todas as despesas pagas para quatro pessoas \u00e0 Spicy Island, de 2 a 6 de julho de 2024!<\/span><\/strong><\/span><\/span><\/span><\/p>\n<h4><strong><span class=\"HwtZe\" lang=\"fr\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">CAM4 te proporcionar\u00e1:<\/span><\/span><\/span><\/strong><\/h4>\n<ul>\n<li>\n<h4><span class=\"HwtZe\" lang=\"fr\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Despesas de viagem at\u00e9 a ilha (passagens de avi\u00e3o, barco, t\u00e1xi, etc.)<\/span><\/span><\/span><\/span><\/h4>\n<\/li>\n<li>\n<h4><span class=\"HwtZe\" lang=\"fr\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Estadia em um luxuoso bangal\u00f4 de dois quartos<\/span><\/span><\/span><\/span><\/h4>\n<\/li>\n<li>\n<h4><span class=\"HwtZe\" lang=\"fr\"> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"><span class=\"HwtZe\" lang=\"pt\">Caf\u00e9 da manh\u00e3, almo\u00e7o e jantar inclu\u00eddos durante a sua estadia.<\/span><\/span><\/span><\/span><\/h4>\n<\/li>\n<li>\n<h4><span class=\"HwtZe\" lang=\"fr\"> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">500\u20ac para gastos na viagem<br \/>\n <\/span><\/span><\/span><\/h4>\n<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60343\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/spicyIs.png\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/spicyIs.png 1000w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicyIs-300x169.png 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicyIs-768x432.png 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicyIs-750x422.png 750w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h4><strong>O Concurso:<\/strong><\/h4>\n<p><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Para participar voc\u00ea deve seguir todos estes passos dentro das duas semanas do concurso:<\/span><\/span><\/span><\/p>\n<h4><strong><em>Semana 1: De 27 de maio a 2 de junho<\/em><\/strong><\/h4>\n<ol>\n<li>\u00a0Dever\u00e1 publicar um <strong>v\u00eddeo<\/strong> (dura\u00e7\u00e3o m\u00ednima 30 segundos) no Twitter com a hashtag <strong>#CAM4Spicyisland<\/strong> e mencionar a conta: <a href=\"https:\/\/twitter.com\/br_cam4\">@<\/a><a href=\"https:\/\/twitter.com\/br_cam4\">br_cam4.<\/a> <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Neste v\u00eddeo voc\u00ea deve se gravar nos contando porque quer ir para a Spicy Island.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adicione tamb\u00e9m um link para o seu perfil CAM4 no tweet<\/span><\/span><\/span><\/li>\n<li>Publique uma <strong>foto sexy de <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">biqu\u00edni ou mai\u00f4<\/span><\/span><\/span><\/strong> no Twitter com a hashtag\u00a0 <strong>#CAM4SpicyIsland<\/strong> e mencionando a conta\u00a0 CAM4 <a href=\"https:\/\/twitter.com\/br_cam4\">@<\/a><a href=\"https:\/\/twitter.com\/br_cam4\">br_cam4<\/a>. <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adicione tamb\u00e9m um link para o seu perfil CAM4 no tweet<\/span><\/span><\/span><\/li>\n<\/ol>\n<h4><strong><em>Semana 2: De 3 a 9 de junho<\/em> <\/strong><\/h4>\n<p>1.\u00a0 Publique um <strong>v\u00eddeo<\/strong> (dura\u00e7\u00e3o m\u00ednima 30 segundos) no Twitter com a hashtag #CAM4Spicyisland e mencione a conta do CAM4 <a href=\"https:\/\/twitter.com\/br_cam4\">@<\/a><a href=\"https:\/\/twitter.com\/br_cam4\">br_cam4<\/a>. <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Neste v\u00eddeo voc\u00ea deve se gravar nos contando sobre o conte\u00fado que vai criar na Spicy Island.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adicione tamb\u00e9m um link para o seu perfil CAM4 no tweet<\/span><\/span><\/span><\/p>\n<p>2.\u00a0Publique uma <strong>foto sexy de biquini ou mai\u00f4<\/strong> no Twitter com a hashtag\u00a0 #CAM4SpicyIsland e mencionando a conta do CAM4\u00a0<a href=\"https:\/\/twitter.com\/br_cam4\">@<\/a><a href=\"https:\/\/twitter.com\/br_cam4\">br_cam4<\/a>. <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adicione tamb\u00e9m um link para o seu perfil CAM4 no tweet<\/span><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60360\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/bdba4_vacay-camera-1.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">No final do concurso, os respons\u00e1veis \u200b\u200bpelas regi\u00f5es Cam4 de <strong>Espanha, Portugal, Fran\u00e7a, Su\u00ed\u00e7a, B\u00e9lgica e It\u00e1lia<\/strong> escolher\u00e3o um \u00fanico vencedor do grande pr\u00eamio.<\/span><\/span><\/span><br \/>\n <em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A decis\u00e3o levar\u00e1 em considera\u00e7\u00e3o a atividade do modelo no Cam4 e seus ganhos durante o concurso (de 27\/05 a 09\/06) e o impacto obtido nas redes por seus v\u00eddeos e fotos publicados.<\/span><\/span><\/span><br \/>\n <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Os resultados ser\u00e3o anunciados at\u00e9 12 de junho de 2024.<\/span><\/span><\/span><br \/>\n <\/em><\/p>\n<p><strong>Regras<\/p>\n<p> &#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Para participar voc\u00ea deve ser uma modelo verificada <\/span><\/span><\/span>\/no CAM4\/ Tempted <br \/>\n <\/strong><\/p>\n<p><strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Voc\u00ea deve mostrar seu rosto (sem m\u00e1scara) em seus shows, v\u00eddeos e publica\u00e7\u00f5es nas redes e aceitar que seu conte\u00fado possa ser publicado em nossas redes.<\/span><\/span><\/span><\/strong><\/p>\n<p> <strong>&#8211; Os\/as participantes <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">devem ter uma conta p\u00fablica no Twitter<\/span><\/span><\/span><\/strong><\/p>\n<p> <strong>&#8211; Os\/as participantes <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">devem se sentir confort\u00e1veis \u200b\u200bem um ambiente liberal e ficar nus com outras pessoas<\/span><\/span><\/span><br \/>\n <\/strong><br \/>\n <strong>&#8211; Os\/as participantes <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">devem residir numa das seguintes regi\u00f5es: Espanha, Portugal, Fran\u00e7a, Su\u00ed\u00e7a, B\u00e9lgica ou It\u00e1lia.<\/span><\/span><\/span><\/strong><\/p>\n<p> <strong> &#8211; Os\/as participantes <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">n\u00e3o devem ter antecedentes criminais ou policiais por qualquer assunto de natureza sexual ou violenta.<\/span><\/span><\/span><\/strong><\/p>\n<p> <strong> &#8211; Os\/as participantes\u00a0 <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">devem ter um passaporte\/cart\u00e3o de identidade v\u00e1lido no momento da viagem.<br \/>\n <\/span><\/span><\/span><\/strong><strong><br \/>\n &#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">As inscri\u00e7\u00f5es ser\u00e3o encerradas em 3 de junho de 2024.<\/span><\/span><\/span><\/strong><\/p>\n<p> <strong>&#8211; <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Ao participar voc\u00ea concorda em realizar uma entrevista para falar sobre sua viagem.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Esta entrevista ser\u00e1 publicada nos blogs e redes sociais do Cam4\/Tempted.<\/span><\/span><\/span><br \/>\n <\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60347\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/spicy3.png\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy3.png 1000w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy3-300x169.png 300w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy3-768x432.png 768w, https:\/\/performers.cam4.com\/wp-content\/uploads\/spicy3-750x422.png 750w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><br \/>\n <span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O que acontece se voc\u00ea vencer?<\/span><\/span><\/span><br \/>\n <\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"fr\"><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O respons\u00e1vel pela sua regi\u00e3o entrar\u00e1 em contato para lhe passar mais informa\u00e7\u00f5es e solicitar:<\/span><\/span><\/span><\/p>\n<p> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">&#8211; <span class=\"HwtZe\" lang=\"pt\">Suas informa\u00e7\u00f5es e documentos pessoais e de seus convidados para fazer reservas de viagens<\/span><br \/>\n <\/span><\/span> &#8211; <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">5 fotos HD SFW <\/span><\/span><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">que podemos usar para sua entrevista e outras promo\u00e7\u00f5es.<\/span><\/span><\/span><br \/>\n <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">&#8211; <span class=\"HwtZe\" lang=\"pt\">Uma lista de perguntas para voc\u00ea responder<\/span><br \/>\n <\/span><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60358\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/25ce9_private-pool.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<p><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O que acontecer\u00e1 durante a viagem?<\/span><\/span><\/span><\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Voc\u00ea poder\u00e1 relaxar e desfrutar da cria\u00e7\u00e3o de conte\u00fado em uma paisagem id\u00edlica pronta para esse fim.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Crie v\u00eddeos e fotos para compartilhar em suas redes sociais, conhe\u00e7a outros criadores de conte\u00fado, divirta-se e expanda sua comunidade internacional gra\u00e7as ao CAM4.<\/span><\/span><\/span><\/p>\n<p><strong><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O que acontecer\u00e1 depois da viagem?<\/span><\/span><\/span><\/strong><\/p>\n<p><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Ao retornar, voc\u00ea ser\u00e1 contatado pela equipe do CAM4 para organizar entrevistas sobre sua viagem, compartilhar fotos\/v\u00eddeos em suas redes que ser\u00e3o compartilhadas nas redes do CAM4 (Youtube, Twitter, Blogs, etc.)<\/span><\/span><\/span><\/p>\n<h5><em><span class=\"HwtZe\" lang=\"pt\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Se voc\u00ea entende as regras e gostaria de participar, digite seu nome de usu\u00e1rio no seguinte formul\u00e1rio:<\/span><\/span><\/span><\/em><\/h5>\n<p><iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeXFXjA12tPTAprbLJ_eOMtopX9sxbHHAbXYuFb1EWgiO8Prg\/viewform?embedded=true\" width=\"640\" height=\"419\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\">Loading\u2026<\/iframe><\/p>\n<h2>Boa sorte a todos e todas!<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-60225 alignnone\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Picture5.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture5.png 624w, https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture5-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-60224 alignnone\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Picture6-1.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture6-1.png 624w, https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture6-1-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-60223 alignnone\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Picture7-1.png\" alt=\"\" width=\"624\" height=\"351\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture7-1.png 624w, https:\/\/performers.cam4.com\/wp-content\/uploads\/Picture7-1-300x169.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/p>\n<div class=\"m-entry__feedback\"><div class=\"m-feedback-prompt\">\n\t\t  <h4 class=\"m-feedback-prompt__header\">Was this article helpful?<\/h4>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt__social m-feedback-prompt__social_thumbsup yes\" data-analytics-link=\"feedback-prompt:yes\">\n\t\t    <i class=\"fa fa-thumbs-up\">&nbsp;<\/i>\n\t\t  <\/a>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt_form no\" data-analytics-link=\"feedback-prompt:no\">\n\t\t    <i class=\"fa fa-thumbs-down\">&nbsp;<\/i>\n\t\t  <\/a><br>\n\t\t  <div class=\"m-feedback-prompt__display m-feedback-prompt__social yes\">\n\t\t    <p class=\"m-feedback-prompt__text\">Awesome, share it:<\/p>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon facebook fa fa-facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Share<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon twitter fa fa-twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/&text=Fa\u00e7a uma viagem libertina para Spicy Island na Cro\u00e1cia com CAM4 &#8211; Ganhadora\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Tweet<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon googleplus fa fa-google-plus\" href=\"https:\/\/plus.google.com\/share?url=https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Google Plus<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon linkedin fa fa-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/&title=Fa\u00e7a uma viagem libertina para Spicy Island na Cro\u00e1cia com CAM4 &#8211; Ganhadora\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">LinkedIn<\/span>\n\t\t    <\/a>\n\t\t  <\/div>\n\t\t  \t<div class=\"m-feedback-prompt__display m-feedback-prompt__form no\">\n\t\t  \t<div class=\"thanks feedback-nodisplayall\"><h2>Thanks!<h2><div class=\"m-contact\"><p>Thanks for getting in touch with us.<\/p><\/div><\/div>\n\t\t    <form id=\"contact-form\" class=\"new_support_request\" action=\"\" accept-charset=\"UTF-8\" method=\"post\">\n\t\t    <input type=\"hidden\" id=\"authenticity_token\" name=\"authenticity_token\" value=\"b21457dabc\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/posts\/60304\" \/>\n\t\t      <input value=\"https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/\" type=\"hidden\" name=\"currenturl\" id=\"currenturl\">\n\t\t      <input value=\"Fa\u00e7a uma viagem libertina para Spicy Island na Cro\u00e1cia com CAM4 &#8211; Ganhadora\" type=\"hidden\" name=\"currenttitle\" id=\"currenttitle\">\n\t\t      <label class=\"is-required\">Help us improve. Give us your feedback:<\/label>\n\t\t      <textarea class=\"p-input__textarea\" name=\"feedbackmessage\" id=\"feedbackmessage\"><\/textarea>\n\t\t      <label class=\"is-required\">Your Full Name:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"feedbackfullname\" id=\"feedbackfullname\">\n\t\t      <label class=\"is-required\">Your email address:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"mailinglistemail\" id=\"mailinglistemail\">\n\t\t      <div class=\"feedback-message\" id=\"feedback-message\"><\/div>\n\t\t      <div class=\"__submit\">\n\t\t        <input type=\"submit\" name=\"commit\" value=\"Submit\" class=\"p-button\" id=\"submit-contact-form\" data-analytics-link=\"feedback-prompt:submit\">\n\t\t      <\/div>\n\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Parab\u00e9ns \u00e0 radiante Nicole_98\u00a0\ud83c\udf1fvencedora da competi\u00e7\u00e3o CAM4 Spicy Island 2024! Clique aqui e descubra quem ela vai levar de f\u00e9rias para a ilha do prazer. \u00a0 Participe do nosso concurso de 27 de maio a 9 de junho de 2024 para ganhar uma viagem onde voc\u00ea poder\u00e1 criar conte\u00fado com at\u00e9 tr\u00eas amigos na Spicy &hellip; <a href=\"https:\/\/performers.cam4.com\/pt-pt\/faca-uma-viagem-libertina-para-spicy-island-na-croacia-com-cam4-de-27-de-maio-a-9-de-junho\/\" class=\"more-link\">Continuar a ler<span class=\"screen-reader-text\">Fa\u00e7a uma viagem libertina para Spicy Island na Cro\u00e1cia com CAM4 &#8211; Ganhadora<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[835,1],"tags":[],"class_list":["post-60304","post","type-post","status-publish","format-standard","hentry","category-cam4-concursos","category-do-not-use"],"acf":[],"_links":{"self":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/60304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=60304"}],"version-history":[{"count":11,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/60304\/revisions"}],"predecessor-version":[{"id":60575,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/posts\/60304\/revisions\/60575"}],"wp:attachment":[{"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=60304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=60304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=60304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}