{"id":75436,"date":"2026-06-03T18:55:46","date_gmt":"2026-06-03T18:55:46","guid":{"rendered":"https:\/\/performers.cam4.com\/?p=75436"},"modified":"2026-06-04T18:50:32","modified_gmt":"2026-06-04T18:50:32","slug":"19-aniversario-do-cam4","status":"publish","type":"post","link":"https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/","title":{"rendered":"Comemore o 19\u00ba anivers\u00e1rio do CAM4 e ganhe 1000 fichas! \u2661 (5-7 Junho)"},"content":{"rendered":"\n<p>Voc\u00ea est\u00e1 oficialmente na lista de convidados para a festa de 19 anos do CAM4!<\/p>\n\n\n\n<p>Comemore o CAM4 com um <strong>show de anivers\u00e1rio sensual <\/strong>neste fim de semana e concorra a um dos <strong>35 pr\u00eamios<\/strong> fotogr\u00e1ficos!<br><\/p>\n\n\n\n<p><strong>de sexta-feira, 5 de junho, a domingo, 7 de junho.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O CAM4 est\u00e1 em festa, mas os presentes s\u00e3o para voc\u00ea!<\/strong><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Birthday_Viewers_Email.jpg\" alt=\"\" class=\"wp-image-75511\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Birthday_Viewers_Email.jpg 700w, https:\/\/performers.cam4.com\/wp-content\/uploads\/PT_Birthday_Viewers_Email-300x169.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n\n\n<p>\u00b7 \u00b7 \u00b7<\/p>\n\n\n\n<p>Neste fim de semana &#8211; <strong>de sexta-feira, 5 de junho, a domingo, 7 de junho<\/strong> &#8211; venha participar das comemora\u00e7\u00f5es com um espet\u00e1culo de bal\u00f5es, prosecco, bolo e todo o equipamento necess\u00e1rio para uma grande festa.<\/p>\n\n\n\n<p>Publique uma foto ou v\u00eddeo no seu feed de atividades. <strong>#CAM4Bday19 para poder ganhar at\u00e9 1000 Fichas!<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/19-1.png\" alt=\"\" class=\"wp-image-75632\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">35 pr\u00eamios para as fotos ou v\u00eddeos mais originais e sensuais, por\u00e9m softs (sem mostrar genitais ou cenas de sexo expl\u00edcitas)<\/h2>\n\n\n\n<p>1 Premio<br>Rainha da festa CAM4<br>1.000 Fichas<\/p>\n\n\n\n<p>1 Pr\u00eamio<br>Rei  da Festa CAM4<br>1.000 Fichas<\/p>\n\n\n\n<p>+<\/p>\n\n\n\n<p>3 Pr\u00eamios<br>500 Fichas<\/p>\n\n\n\n<p>+<\/p>\n\n\n\n<p>5 Pr\u00eamios<\/p>\n\n\n\n<p>250 Fichas<\/p>\n\n\n\n<p>+<\/p>\n\n\n\n<p>25 pr\u00eamios<\/p>\n\n\n\n<p>100 Fichas<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/cake-white.png\" alt=\"\" width=\"60\" height=\"60\"><\/p>\n\n\n\n<p>Ao final do concurso, os gestores de comunidade de todos os pa\u00edses participantes do CAM4 avaliar\u00e3o as fotos com base na qualidade e criatividade do conte\u00fado. As 35 modelos de webcam concorrentes com as maiores pontua\u00e7\u00f5es ganhar\u00e3o um dos pr\u00eamios.<\/p>\n\n\n\n<p>\u00b7 \u00b7 \u00b7<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>~ <\/strong>Como participar do concurso para ganhar um dos pr\u00eamios &gt;&gt;&gt; Siga estes 2 passos:<\/h2>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Champagne-Glass.png\" alt=\"\" width=\"80\" height=\"80\"><\/p>\n\n\n\n<p><strong>\u2764 Agende  <a href=\"https:\/\/pt.cam4.com\/training\/iniciando-cam4\/como-agendar-seus-shows\">no seu calend\u00e1rio de transmiss\u00e3o CAM4<\/a> um show a ser realizado*5, 6 ou 7 de Junho* inserindo na descri\u00e7\u00e3o: #Cam4Bday19<\/strong><\/p>\n\n\n\n<p>Shows n\u00e3o previamente agendados n\u00e3o ser\u00e3o inscritos na competi\u00e7\u00e3o nem receber\u00e3o quaisquer pr\u00eamios.<\/p>\n\n\n\n<p>\u2764 Durante o seu show (ou um pouco antes)<br>, <strong>publique no seu Feed de Atividades do Cam4 uma foto ou v\u00eddeo soft<\/strong> (sem mostrar os genitais) do tema de festa de anivers\u00e1rio, e insira na descri\u00e7\u00e3o: <strong>#CAM4Bday19<\/strong><img decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/ballons.jpg\" alt=\"Ballons\"><\/p>\n\n\n\n<p>Para publicar uma foto ou v\u00eddeo no seu feed de atividades, clique no canto superior direito. <strong>+ Novo Post<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"215\" src=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/image-27.png\" alt=\"\" class=\"wp-image-75537\" srcset=\"https:\/\/performers.cam4.com\/wp-content\/uploads\/image-27.png 407w, https:\/\/performers.cam4.com\/wp-content\/uploads\/image-27-300x158.png 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div>\n\n\n<p>Em seguida, envie sua foto ou v\u00eddeo SOFT (sem sexo expl\u00edcito ou genitais vis\u00edveis). Escreva sua mensagem pessoal (incluindo <strong>#CAM4Bday19<\/strong>) e clique em <strong>Publica<\/strong>r.<img decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/bday-post.jpg\" alt=\"Activity Feed Post\"><\/p>\n\n\n\n<p><em>Lembre-se de n\u00e3o definir nenhum pre\u00e7o, para que sua publica\u00e7\u00e3o fique vis\u00edvel.<\/em><\/p>\n\n\n\n<p>\u00b7 \u00b7 \u00b7<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">~ Ideias para um show com tema de anivers\u00e1rio<\/h2>\n\n\n\n<p>Lembre-se, o tema dos shows, v\u00eddeos e fotos \u00e9 <strong>festa<\/strong>! Vista-se com eleg\u00e2ncia, ou com um visual extravagante, por exemplo! O que seria de uma festa sem bolo ou espumante para o brinde? Aqui est\u00e3o mais algumas ideias para a sua festa:<\/p>\n\n\n\n<p><strong>~ O numero <em>19!<\/em><\/strong><em> P<\/em><em>ara velas, bal\u00f5es, decora\u00e7\u00f5es&#8230;<\/em><br><strong>~ Brinque com chocolate, morangos e creme!<\/strong><img decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/bday1-2.jpg\" alt=\"Birthday Ideas\"><\/p>\n\n\n\n<p>~ Mostre seu look de festa, vista-se bem ou use uma m\u00e1scara sexy.<br>~ Brinque de estourar bal\u00f5es como recompensa por jogar seus jogos no chat!<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/e4fae_cake-16-2023-alt-1.png\" alt=\"\"><\/p>\n\n\n\n<p><strong>Conselho TOP:<br>Publique v\u00eddeos ou fotos criativas em alta resolu\u00e7\u00e3o e com \u00e2ngulos impactantes. N\u00e3o adicione logotipos ou texto \u00e0s suas fotos. Lembre-se: voc\u00ea pode publicar v\u00e1rias fotos para aumentar suas chances de ganhar um dos pr\u00eamios!<\/strong><\/p>\n\n\n\n<p><strong>Lembre-se que para este concurso voc\u00ea deve usar conte\u00fado SOFT:<br>&#8211; N\u00c3O \u00c9 PERMITIDO: Genitais ou sexo expl\u00edcito<br>&#8211; PERMITIDO: Seios \/ Bunda<\/strong><\/p>\n\n\n\n<p><strong>Compartilhe sua foto tamb\u00e9m no X (Twitter) para obter mais visibilidade e mais visualiza\u00e7\u00f5es!<\/strong><img decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Sexylatinogay.jpg\" alt=\"Inspiraci\u00f3n\"><\/p>\n\n\n\n<p><a href=\"https:\/\/pt.cam4.com\/blog\/as-fotos-mais-iconicas-do-aniversario-de-18-anos-do-cam4-%f0%9f%8d%be\/\"><em>Precisa de inspira\u00e7\u00e3o? Confira as fotos vencedoras do ano passado!<\/em><\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/performers.cam4.com\/wp-content\/uploads\/Cataleya_666-02-4.jpg\" alt=\"CAM4 Birthday\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>~ Regras:<\/strong><\/h2>\n\n\n\n<p>Somente modelos com conta verificada em seu Performer Dashoard podem participar.<\/p>\n\n\n\n<p>O show dever\u00e1 ser agendado com anteced\u00eancia no calend\u00e1rio de transmiss\u00f5es com a descri\u00e7\u00e3o: <strong>#CAM4Bday19<\/strong>.<\/p>\n\n\n\n<p>O show dever\u00e1 ser realizado ao vivo no CAM4 entre os dias <strong>5 e 7 de junho<\/strong>.<\/p>\n\n\n\n<p>Lembre-se de inserir <strong>#CAM4Bday19<\/strong> como descri\u00e7\u00e3o da sua publica\u00e7\u00e3o (foto ou v\u00eddeo) no feed.<\/p>\n\n\n\n<p>O show e as fotos publicadas dever\u00e3o ter o tema <strong>festa de anivers\u00e1rio sexy<\/strong>. (Se a foto n\u00e3o estiver de acordo com o tema, n\u00e3o ser\u00e1 considerada v\u00e1lida.)<\/p>\n\n\n\n<p>As fotos \/ v\u00eddeos \/ GIFs devem ser leves (<strong>SFW \u2013 Safe For Work<\/strong>). Isso significa: sem genitais ou sexo expl\u00edcito. (Seios, mamilos e n\u00e1degas s\u00e3o permitidos.)<\/p>\n\n\n\n<p>As fotos ou v\u00eddeos publicados dever\u00e3o ser conte\u00fados novos. N\u00e3o \u00e9 permitido participar com fotos j\u00e1 utilizadas anteriormente em concursos.<\/p>\n\n\n\n<p>M\u00e1ximo de um pr\u00eamio por modelo (solo ou casal), mesmo que seja realizado mais de um show.<\/p>\n\n\n\n<p>Os pr\u00eamios ser\u00e3o adicionados \u00e0 conta at\u00e9 <strong>14 de junho<\/strong> e estar\u00e3o vis\u00edveis no Painel de Performer, na se\u00e7\u00e3o <strong>Estat\u00edsticas<\/strong> (na parte inferior).<\/p>\n\n\n\n<p>Os vencedores das melhores fotos receber\u00e3o uma mensagem de notifica\u00e7\u00e3o e concordam que suas fotos sejam publicadas no blog da CAM4 e nas redes sociais.<\/p>\n\n\n\n<p>Ao participar, voc\u00ea concorda que sua foto ou v\u00eddeo possa ser utilizado pela CAM4 em nossos canais sociais e em nosso blog para eventual promo\u00e7\u00e3o dos conte\u00fados.<\/p>\n\n\n\n<p><strong>Observa\u00e7\u00e3o:<\/strong> Somente performers que tiverem ganho pelo menos <strong>US$ 50 (500 Fichas)<\/strong> no per\u00edodo de <strong>7 de maio a 7 de junho de 2026<\/strong> poder\u00e3o se qualificar para ganhar um dos pr\u00eamios no valor de <strong>500 Fichas<\/strong> e <strong>1000 Fichas<\/strong>. Os performers que tiverem ganhado menos de <strong>500 Fichas<\/strong> nos 30 dias anteriores ao concurso ainda poder\u00e3o ganhar um dos pr\u00eamios de <strong>US$ 25<\/strong> ou <strong>US$ 10<\/strong>.<\/p>\n<div class=\"m-entry__feedback\"><div class=\"m-feedback-prompt\">\n\t\t  <h4 class=\"m-feedback-prompt__header\">Was this article helpful?<\/h4>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt__social m-feedback-prompt__social_thumbsup yes\" data-analytics-link=\"feedback-prompt:yes\">\n\t\t    <i class=\"fa fa-thumbs-up\">&nbsp;<\/i>\n\t\t  <\/a>\n\t\t  <a href=\"#\" class=\"m-feedback-prompt__button m-feedback-prompt_form no\" data-analytics-link=\"feedback-prompt:no\">\n\t\t    <i class=\"fa fa-thumbs-down\">&nbsp;<\/i>\n\t\t  <\/a><br>\n\t\t  <div class=\"m-feedback-prompt__display m-feedback-prompt__social yes\">\n\t\t    <p class=\"m-feedback-prompt__text\">Awesome, share it:<\/p>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon facebook fa fa-facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Share<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon twitter fa fa-twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/&text=Comemore o 19\u00ba anivers\u00e1rio do CAM4 e ganhe 1000 fichas! \u2661 (5-7 Junho)\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Tweet<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon googleplus fa fa-google-plus\" href=\"https:\/\/plus.google.com\/share?url=https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">Google Plus<\/span>\n\t\t    <\/a>\n\t\t    <a class=\"m-feedback-prompt__social--button p-button-social has-icon linkedin fa fa-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/&title=Comemore o 19\u00ba anivers\u00e1rio do CAM4 e ganhe 1000 fichas! \u2661 (5-7 Junho)\" onclick=\"javascript:window.open(this.href,\n  '', 'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600');return false;\">\n\t\t      <span class=\"p-button-social__social-text\">LinkedIn<\/span>\n\t\t    <\/a>\n\t\t  <\/div>\n\t\t  \t<div class=\"m-feedback-prompt__display m-feedback-prompt__form no\">\n\t\t  \t<div class=\"thanks feedback-nodisplayall\"><h2>Thanks!<h2><div class=\"m-contact\"><p>Thanks for getting in touch with us.<\/p><\/div><\/div>\n\t\t    <form id=\"contact-form\" class=\"new_support_request\" action=\"\" accept-charset=\"UTF-8\" method=\"post\">\n\t\t    <input type=\"hidden\" id=\"authenticity_token\" name=\"authenticity_token\" value=\"b21457dabc\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-br\/wp-json\/wp\/v2\/posts\/75436\" \/>\n\t\t      <input value=\"https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/\" type=\"hidden\" name=\"currenturl\" id=\"currenturl\">\n\t\t      <input value=\"Comemore o 19\u00ba anivers\u00e1rio do CAM4 e ganhe 1000 fichas! \u2661 (5-7 Junho)\" type=\"hidden\" name=\"currenttitle\" id=\"currenttitle\">\n\t\t      <label class=\"is-required\">Help us improve. Give us your feedback:<\/label>\n\t\t      <textarea class=\"p-input__textarea\" name=\"feedbackmessage\" id=\"feedbackmessage\"><\/textarea>\n\t\t      <label class=\"is-required\">Your Full Name:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"feedbackfullname\" id=\"feedbackfullname\">\n\t\t      <label class=\"is-required\">Your email address:<\/label>\n\t\t      <input class=\"p-input__text\" type=\"text\" name=\"mailinglistemail\" id=\"mailinglistemail\">\n\t\t      <div class=\"feedback-message\" id=\"feedback-message\"><\/div>\n\t\t      <div class=\"__submit\">\n\t\t        <input type=\"submit\" name=\"commit\" value=\"Submit\" class=\"p-button\" id=\"submit-contact-form\" data-analytics-link=\"feedback-prompt:submit\">\n\t\t      <\/div>\n\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea est\u00e1 oficialmente na lista de convidados para a festa de 19 anos do CAM4! Comemore o CAM4 com um show de anivers\u00e1rio sensual neste fim de semana e concorra a um dos 35 pr\u00eamios fotogr\u00e1ficos! de sexta-feira, 5 de junho, a domingo, 7 de junho. O CAM4 est\u00e1 em festa, mas os presentes s\u00e3o &hellip; <a href=\"https:\/\/performers.cam4.com\/pt-br\/19-aniversario-do-cam4\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Comemore o 19\u00ba anivers\u00e1rio do CAM4 e ganhe 1000 fichas! \u2661 (5-7 Junho)<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[843,770],"tags":[],"class_list":["post-75436","post","type-post","status-publish","format-standard","hentry","category-competicoes-cam4","category-concursos-no-site"],"acf":[],"_links":{"self":[{"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/posts\/75436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/comments?post=75436"}],"version-history":[{"count":9,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/posts\/75436\/revisions"}],"predecessor-version":[{"id":75645,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/posts\/75436\/revisions\/75645"}],"wp:attachment":[{"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/media?parent=75436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/categories?post=75436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/performers.cam4.com\/pt-br\/wp-json\/wp\/v2\/tags?post=75436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}